{"id":46,"count":1,"description":"","link":"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/","name":"aerobic exercise","slug":"aerobic-exercise","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>aerobic exercise Archives - SYNRGY FITNESS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"aerobic exercise Archives - SYNRGY FITNESS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/\" \/>\n<meta property=\"og:site_name\" content=\"SYNRGY FITNESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/\",\"url\":\"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/\",\"name\":\"aerobic exercise Archives - SYNRGY FITNESS\",\"isPartOf\":{\"@id\":\"https:\/\/synrgy.fitness\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/synrgy.fitness\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"aerobic exercise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/synrgy.fitness\/blog\/#website\",\"url\":\"https:\/\/synrgy.fitness\/blog\/\",\"name\":\"SYNRGY FITNESS\",\"description\":\"Articles by SYNRGY FITNESS\",\"publisher\":{\"@id\":\"https:\/\/synrgy.fitness\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/synrgy.fitness\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/synrgy.fitness\/blog\/#organization\",\"name\":\"Synrgy Fitness\",\"url\":\"https:\/\/synrgy.fitness\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/synrgy.fitness\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/synrgy.fitness\/public\/blog\/wp-content\/uploads\/2020\/12\/synrgy-logo-grey-on-white-01.png\",\"contentUrl\":\"https:\/\/synrgy.fitness\/public\/blog\/wp-content\/uploads\/2020\/12\/synrgy-logo-grey-on-white-01.png\",\"width\":1080,\"height\":511,\"caption\":\"Synrgy Fitness\"},\"image\":{\"@id\":\"https:\/\/synrgy.fitness\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/synrgy.fitness\",\"https:\/\/www.instagram.com\/synrgy.fitness\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"aerobic exercise Archives - SYNRGY FITNESS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/","og_locale":"en_GB","og_type":"article","og_title":"aerobic exercise Archives - SYNRGY FITNESS","og_url":"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/","og_site_name":"SYNRGY FITNESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/","url":"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/","name":"aerobic exercise Archives - SYNRGY FITNESS","isPartOf":{"@id":"https:\/\/synrgy.fitness\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/synrgy.fitness\/blog\/tag\/aerobic-exercise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/synrgy.fitness\/blog\/"},{"@type":"ListItem","position":2,"name":"aerobic exercise"}]},{"@type":"WebSite","@id":"https:\/\/synrgy.fitness\/blog\/#website","url":"https:\/\/synrgy.fitness\/blog\/","name":"SYNRGY FITNESS","description":"Articles by SYNRGY FITNESS","publisher":{"@id":"https:\/\/synrgy.fitness\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/synrgy.fitness\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/synrgy.fitness\/blog\/#organization","name":"Synrgy Fitness","url":"https:\/\/synrgy.fitness\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/synrgy.fitness\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/synrgy.fitness\/public\/blog\/wp-content\/uploads\/2020\/12\/synrgy-logo-grey-on-white-01.png","contentUrl":"https:\/\/synrgy.fitness\/public\/blog\/wp-content\/uploads\/2020\/12\/synrgy-logo-grey-on-white-01.png","width":1080,"height":511,"caption":"Synrgy Fitness"},"image":{"@id":"https:\/\/synrgy.fitness\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/synrgy.fitness","https:\/\/www.instagram.com\/synrgy.fitness"]}]}},"_links":{"self":[{"href":"https:\/\/synrgy.fitness\/blog\/wp-json\/wp\/v2\/tags\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/synrgy.fitness\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/synrgy.fitness\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/synrgy.fitness\/blog\/wp-json\/wp\/v2\/posts?tags=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}